{"id":104465,"date":"2025-08-08T12:57:10","date_gmt":"2025-08-08T10:57:10","guid":{"rendered":"https:\/\/www.romeing.it\/gli-appuntamenti-estivi-di-villa-medici\/"},"modified":"2025-12-18T17:25:11","modified_gmt":"2025-12-18T16:25:11","slug":"gli-appuntamenti-estivi-di-villa-medici","status":"publish","type":"post","link":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/","title":{"rendered":"Gli appuntamenti estivi di Villa Medici"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-scopri-il-programma-per-l-estate-2025-di-villa-medici-a-roma\">Scopri il programma per l&#8217;estate 2025 di Villa Medici a Roma!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Villa Medici &#8211; Accademia di Francia a Roma<\/strong>, \u00e8 una prestigiosa sede museale e culturale che si trova vicino a <strong>Villa Borghese<\/strong>. Come ogni estate anche quest&#8217;anno \u00e8 pronta a ospitare numerosi eventi, con un ricchissimo programma che si snoda tra <strong>mostre d&#8217;arte, interventi di architettura del paesaggio e festival cinematografici<\/strong>. Con <strong>18 ettari di giardini<\/strong>, fontane e sculture, Villa Medici rimane un&#8217;oasi di espressione artistica che ricorda la campagna francese, pur affacciandosi su una delle zone pi\u00f9 centrali di Roma. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Scopriamo di seguito la programmazione artistica di Villa Medici da Maggio a Settembre 2025.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.tiqets.com\/en\/rome-attractions-c71631\/tickets-for-villa-medici-entry-p1075040\/?partner=romeing&amp;tq_campaign=villa+medici\" target=\"_blank\" rel=\"noreferrer noopener\">PRENOTA IL TOUR GUIDATO DI VILLA MEDICI<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-festival-des-cabanes-di-villa-medici-5-giugno-29-settembre-2025\">Festival des Cabanes di Villa Medici | 5 Giugno &#8211; 29 Settembre 2025<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/25-05-02_Festival-des-cabanes_@Daniele-Molajoli_Huttopia_05-1-1024x768.jpg\" alt=\"Festival-des-cabanes\" class=\"wp-image-177349\"\/><figcaption class=\"wp-element-caption\">Huttopia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>Festival des Cabanes di Villa Medici<\/strong> nasce per offrire la possibilit\u00e0 a architetti, artisti e ricercatori di &#8220;prendere possesso&#8221; dei giardini storici del sito, progettati da Ferdinando de&#8217; Medici alla fine del XVI secolo. Per il quarto anno consecutivo cinque creazioni originali di &#8220;capanne&#8221; troveranno spazio per tutta l&#8217;estate nel cuore dei giardini di Villa Medici, progettati appositamente per il festival da gruppi internazionali di architetti, costruttori e studenti: <strong><strong>Associates Architecture, Atelier MARE, Campo &amp; Diploma 20 Architectural Association with artist Roger Ballen, Huttopia, e MBL architectes<\/strong>.<\/strong>. Per tutta l\u2019estate, le capanne accoglieranno diversi laboratori pedagogici, letture e corsi di yoga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Giorni e orari di apertura della mostra:<br><\/strong>Dal luned\u00ec alla domenica (chiuso il marted\u00ec) tra le 10:00 e le 19:00 (ultimo ingresso alle 18:30)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tariffa:<br><\/strong>Prezzo intero: 8\u20ac \/ Prezzo ridotto: 6\u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cambiare-la-prosa-del-mondo-mostra-dei-borsisti-di-villa-medici-28-giugno-8-settembre-2025\">Cambiare la Prosa del Mondo \/ Mostra dei borsisti di Villa Medici | 28 Giugno &#8211; 8 Settembre 2025<\/h3>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/Villa-medici-2.jpg\" alt=\"Cambiare la prosa del mondo \" class=\"wp-image-178709\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dal <strong>28 giugno<\/strong> all\u2019<strong>8 settembre 2025<\/strong>, Villa Medici \u2013 Accademia di Francia a Roma ospita <em>Cambiare la prosa del mondo<\/em>, l\u2019esposizione collettiva che riunisce i progetti dei 16 borsisti alla conclusione del loro anno di residenza. Curata da <strong>Lilou Vidal<\/strong>, la mostra prende il titolo dal verso di una poesia di <strong>Amelia Rosselli<\/strong>, evocando la necessit\u00e0 di riformulare le narrazioni dominanti attraverso forme artistiche e poetiche dissidenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In un percorso interdisciplinare che include arti visive, fotografia, letteratura, musica e cinema, i testi selezionati dagli artisti sono disposti lungo le pareti grazie all\u2019intervento tipografico di <strong>Montasser Drissi<\/strong>, trasformando gli spazi in un racconto fluido e corale. Le opere, concepite nei loro atelier, dialogano ora direttamente con il pubblico e si offrono come un laboratorio vivo di ricerca politica, ecologica e poetica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Orari di apertura della mostra:<\/strong><br>Dal luned\u00ec alla domenica (chiuso il marted\u00ec) dalle 10:00 alle 19:00 (ultimo ingresso alle 18:30).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tariffe:<\/strong><br>Intero: \u20ac10 \/ Ridotto: \u20ac8<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/villamedici.it\/it\/programme\/cambiare-la-prosa-del-mondo\" target=\"_blank\" rel=\"noreferrer noopener\">villamedici.it\/it\/programme\/cambiare-la-prosa-del-mondo<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-villa-medici-film-festival-10-14-settembre-2025\">Villa Medici Film Festival | 10 &#8211; 14 Settembre 2025<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/\u00a9-Margherita-Nuti-Daniele-Molajoli1-1-1024x683.jpg\" alt=\"Villa Medici Film Festival\" class=\"wp-image-139968\"\/><figcaption class=\"wp-element-caption\">\u00a9 Margherita Nuti -Daniele Molajoli<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nato nel 2021, il <a href=\"https:\/\/www.romeing.it\/it\/villa-medici-film-festival\/\">Villa Medici Film Festival<\/a> offre una selezione internazionale di film che esplora i legami tra il cinema e l&#8217;arte contemporanea. Per il quinto anno consecutivo, il festival si propone di offrire opere pionieristiche dai profili variegati che mettono in discussione, sconvolgono, stravolgono o re-incantano il nostro rapporto con le immagini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>Villa Medici Film Festival<\/strong> \u00e8 diviso in tre sezioni:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la&nbsp;<strong>competizione internazionale<\/strong>, composta di quattordici film, di ogni formato e genere (documentario, fiction, saggio), realizzati durante l\u2019anno precedente il Festival e provenienti dai cinque continenti.<\/li>\n\n\n\n<li>la&nbsp;<strong>selezione Focus<\/strong>, con masterclass, performance e proiezioni di film di artisti fuori la competizione.<\/li>\n\n\n\n<li>le&nbsp;<strong>proiezioni del Piazzale<\/strong>, film recenti presentati ogni sera nel cortile principale di Villa Medici (<em>Piazzale<\/em>) e pensati per riunire tutti gli spettatori.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>Concorso Internazionale<\/strong> presenta ogni anno <strong>12 film<\/strong> di ogni lunghezza e genere (documentario, fiction, saggio). La giuria, che quest&#8217;anno \u00e8 composta da Alain Guiraudie, Guslagie Malanda, e Anri Sala, assegner\u00e0 due premi: <strong>il Premio per il miglior film e il Premio della giuria.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.tiqets.com\/en\/rome-attractions-c71631\/tickets-for-villa-medici-entry-p1075040\/?partner=romeing&amp;tq_campaign=villa+medici\" target=\"_blank\" rel=\"noreferrer noopener\">PRENOTA IL TOUR GUIDATO DI VILLA MEDICI<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Villa Medici<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Viale della Trinit\u00e0 dei Monti, 1<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"http:\/\/www.villamedici.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.villamedici.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri il programma degli eventi estivi a Villa Medici per il 2025, tra mostre d&#8217;arte, interventi di architettura del paesaggio e cinema.<\/p>\n","protected":false},"author":1576,"featured_media":53588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[597,580,592],"tags":[],"class_list":["post-104465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema-sport-roma","category-eventi-a-roma","category-mostre-a-roma"],"featured_image_src":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gli appuntamenti estivi di Villa Medici - Romeing<\/title>\n<meta name=\"description\" content=\"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d&#039;arte, interventi di architettura del paesaggio e cinema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli appuntamenti estivi di Villa Medici\" \/>\n<meta property=\"og:description\" content=\"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d&#039;arte, interventi di architettura del paesaggio e cinema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/\" \/>\n<meta property=\"og:site_name\" content=\"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Romeing.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-08T10:57:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T16:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina Martinoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@romeing\" \/>\n<meta name=\"twitter:site\" content=\"@romeing\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina Martinoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/\"},\"author\":{\"name\":\"Valentina Martinoli\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\"},\"headline\":\"Gli appuntamenti estivi di Villa Medici\",\"datePublished\":\"2025-08-08T10:57:10+00:00\",\"dateModified\":\"2025-12-18T16:25:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/\"},\"wordCount\":625,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/villa-medici-programma-estivo.jpg\",\"articleSection\":[\"Cinema e Sport\",\"Eventi a Roma\",\"Mostre\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/\",\"name\":\"Gli appuntamenti estivi di Villa Medici - Romeing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/villa-medici-programma-estivo.jpg\",\"datePublished\":\"2025-08-08T10:57:10+00:00\",\"dateModified\":\"2025-12-18T16:25:11+00:00\",\"description\":\"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d'arte, interventi di architettura del paesaggio e cinema.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/gli-appuntamenti-estivi-di-villa-medici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/villa-medici-programma-estivo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/villa-medici-programma-estivo.jpg\",\"width\":1200,\"height\":799,\"caption\":\"Summer events at Villa Medici\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"name\":\"Romeing: Rome's english magazine, events and exhibitions in Rome\",\"description\":\"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\",\"name\":\"Romeing srl\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"width\":696,\"height\":696,\"caption\":\"Romeing srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Romeing.it\",\"https:\\\/\\\/x.com\\\/romeing\",\"https:\\\/\\\/www.instagram.com\\\/romeing_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/romeing-srl\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/romeing\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@RomeingIt\"],\"email\":\"info@romeing.it\",\"legalName\":\"Romeing Srl\",\"foundingDate\":\"2010-12-01\",\"vatID\":\"11115241009\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\",\"name\":\"Valentina Martinoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"caption\":\"Valentina Martinoli\"},\"description\":\"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \\\"Beauty will save the world\\\".\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/author\\\/katiba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gli appuntamenti estivi di Villa Medici - Romeing","description":"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d'arte, interventi di architettura del paesaggio e cinema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/","og_locale":"it_IT","og_type":"article","og_title":"Gli appuntamenti estivi di Villa Medici","og_description":"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d'arte, interventi di architettura del paesaggio e cinema.","og_url":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/","og_site_name":"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome","article_publisher":"https:\/\/www.facebook.com\/Romeing.it","article_published_time":"2025-08-08T10:57:10+00:00","article_modified_time":"2025-12-18T16:25:11+00:00","og_image":[{"width":1200,"height":799,"url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","type":"image\/jpeg"}],"author":"Valentina Martinoli","twitter_card":"summary_large_image","twitter_creator":"@romeing","twitter_site":"@romeing","twitter_misc":{"Scritto da":"Valentina Martinoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#article","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/"},"author":{"name":"Valentina Martinoli","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a"},"headline":"Gli appuntamenti estivi di Villa Medici","datePublished":"2025-08-08T10:57:10+00:00","dateModified":"2025-12-18T16:25:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/"},"wordCount":625,"commentCount":0,"publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"image":{"@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","articleSection":["Cinema e Sport","Eventi a Roma","Mostre"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.romeing.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/","url":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/","name":"Gli appuntamenti estivi di Villa Medici - Romeing","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#primaryimage"},"image":{"@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","datePublished":"2025-08-08T10:57:10+00:00","dateModified":"2025-12-18T16:25:11+00:00","description":"Scopri il programma degli eventi estivi a Villa Medici per il 2025 tra mostre d'arte, interventi di architettura del paesaggio e cinema.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/gli-appuntamenti-estivi-di-villa-medici\/#primaryimage","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg","width":1200,"height":799,"caption":"Summer events at Villa Medici"},{"@type":"WebSite","@id":"https:\/\/www.romeing.it\/it\/#website","url":"https:\/\/www.romeing.it\/it\/","name":"Romeing: Rome's english magazine, events and exhibitions in Rome","description":"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.","publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.romeing.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.romeing.it\/it\/#organization","name":"Romeing srl","url":"https:\/\/www.romeing.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","width":696,"height":696,"caption":"Romeing srl"},"image":{"@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Romeing.it","https:\/\/x.com\/romeing","https:\/\/www.instagram.com\/romeing_magazine\/","https:\/\/www.linkedin.com\/company\/romeing-srl\/","https:\/\/www.pinterest.it\/romeing\/pins\/","https:\/\/www.youtube.com\/@RomeingIt"],"email":"info@romeing.it","legalName":"Romeing Srl","foundingDate":"2010-12-01","vatID":"11115241009"},{"@type":"Person","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a","name":"Valentina Martinoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","caption":"Valentina Martinoli"},"description":"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \"Beauty will save the world\".","url":"https:\/\/www.romeing.it\/it\/author\/katiba\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg",1200,799,false],"thumbnail":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo-150x150.jpg",150,150,true],"medium":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo-768x511.jpg",768,511,true],"large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo-1024x682.jpg",800,533,true],"1536x1536":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg",1200,799,false],"2048x2048":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/villa-medici-programma-estivo.jpg",1200,799,false]},"uagb_author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"uagb_comment_info":0,"uagb_excerpt":"Scopri il programma degli eventi estivi a Villa Medici per il 2025, tra mostre d'arte, interventi di architettura del paesaggio e cinema.","_links":{"self":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/104465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/users\/1576"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/comments?post=104465"}],"version-history":[{"count":1,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/104465\/revisions"}],"predecessor-version":[{"id":104466,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/104465\/revisions\/104466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media\/53588"}],"wp:attachment":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media?parent=104465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/categories?post=104465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/tags?post=104465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}