{"id":105083,"date":"2024-10-31T09:33:42","date_gmt":"2024-10-31T09:33:42","guid":{"rendered":"https:\/\/www.romeing.it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/"},"modified":"2025-12-03T20:27:48","modified_gmt":"2025-12-03T20:27:48","slug":"roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi","status":"publish","type":"post","link":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/","title":{"rendered":"ROMA PITTRICE. Artiste al lavoro tra XVI e XVIII secolo in mostra a Palazzo Braschi"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-l-arte-vista-al-femminile-in-una-ricca-mostra-con-piu-di-130-opere-che-percorrono-due-secoli-di-storia\">L&#8217;arte vista al femminile in una ricca mostra con pi\u00f9 di 130 opere che percorrono due secoli di storia<\/h2>\n\n\n\n<p>La presenza artistica&nbsp;delle donne&nbsp;nella Roma&nbsp;capitale delle&nbsp;Arti tra XVI e XIX secolo \u00e8 al centro della <a href=\"https:\/\/www.romeing.it\/it\/mostre-a-roma\/\">mostra<\/a> <strong><em>Roma Pittrice. Artiste al lavoro tra XVI e XVIII secolo<\/em><\/strong>, nelle sale del <strong>Museo di Roma a Palazzo Braschi<\/strong> fino al prossimo <strong>4 maggio<\/strong>. Un percorso di <strong>oltre 130 opere<\/strong>, alcune inedite o esposte per la prima volta, per raccontare le tante artiste che dal XVI al XIX secolo hanno fatto di Roma il loro luogo di studio e di lavoro con una produzione ricca, variegata e di assoluto rilievo artistico, spesso purtroppo relegate a una sorta di \u201csilenzio\u201d storiografico.<\/p>\n\n\n\n<p>Sono <strong>cinquantasei le artiste<\/strong> presenti nella mostra, che ripercorre le loro vicende professionali e biografiche, spesso ignote a causa della mancanza di documentazione o perch\u00e9 le loro opere erano state attribuite ai lavori di maestri e familiari uomini. <strong>Maria Felice Tibaldi Subleyras<\/strong>, <strong>Angelika Kaufmann, Laura Piranesi, Marianna Candidi Dionigi, Louise Seidler <\/strong>ed<strong> Emma Gaggiotti<\/strong>; e ancora le notissime <strong>Lavinia Fontana, Artemisia Gentileschi e Giovanna Garzoni<\/strong>, insieme alle meno conosciute <strong>Giustiniana Guidotti, Ida Botti o Amalia De Angelis<\/strong> e molte altre.<\/p>\n\n\n\n<p>Il percorso, cronologico e tematico, descrive <strong>il progressivo inserimento di queste pittrici nel mercato internazionale<\/strong>, e il faticoso conseguimento del pieno accesso alla formazione e alle pi\u00f9 importanti istituzioni della citt\u00e0, quali l\u2019<em>Accademia di San Luca<\/em> e l\u2019<em>Accademia dei Virtuosi al Pantheon<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/09\/SEIDLER-Luise_Ritratto-di-Dorothea-Denecke-von-Ramdohr-con-la-figlia-Lilli-1819.jpg\" alt=\"ROMA PITTRICE. Artiste al lavoro tra XVI e XIX secolo\" class=\"wp-image-167192\"\/><figcaption class=\"wp-element-caption\">Luise Seidler (1786 Jena &#8211; 1866 Weimar)\nRitratto di Dorothea Denecke von Ramdohr con la figlia Lilli\n1819, Olio su tela, 118,5 x 96,2 cm\nRoma, Museo di Roma a Palazzo Braschi<\/figcaption><\/figure>\n\n\n\n<p>La prima sala \u00e8 dedicata alla bolognese <strong>Lavinia Fontana<\/strong>, seguita dal talento indiscusso di <strong>Artemisia Gentileschi<\/strong>, di cui spicca la <em>Giuditta e la serva con la testa di Oloferne<\/em>, riproposizione con toni pi\u00f9 tenebrosi di un dipinto del padre Orazio.<\/p>\n\n\n\n<p>Importante la presenza di <strong>Giustiniana Guidotti<\/strong>, con l\u2019unica opera da lei realizzata sinora nota, esposta qui per la prima volta. Il Seicento \u00e8 ben rappresentato dalle nature morte di <strong>Laura Bernasconi, Anna Stanchi<\/strong> e <strong>Giovanna Garzoni<\/strong> oltre che dalla sezioni dedicate al ritratto, alla grafica<em> <\/em>e alla miniatura.<\/p>\n\n\n\n<p>Attraverso cinque dipinti viene illustrato poi il percorso artistico di <strong>Angelika Kauffmann<\/strong>, pittrice internazionale che si stabilisce a Roma, dove la sua casa-atelier diventa un luogo di incontro per tanti intellettuali.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome-1024x683.jpg\" alt=\"ROMA PITTRICE. Artiste al lavoro tra XVI e XIX secolo\" class=\"wp-image-167196\"\/><\/figure>\n\n\n\n<p>Ampio spazio, poi, all\u2019incisora <strong>Laura Piranesi <\/strong>e altre pittrici che, con il loro operato, consolidano la presenza nelle accademie e il successo nel mercato dell&#8217;arte, tra cui <strong>\u00c9lisabeth Vig\u00e9e, Caterina Cherubini e Maria Felice Tibaldi<\/strong>. Di <strong>Emma Gaggiotti<\/strong> si espone per la prima volta il <em>Ritratto di famiglia<\/em>, oltre alla <em>Venere<\/em> degli Uffizi e la <em>Sacra Famiglia<\/em> dei Vaticani.<\/p>\n\n\n\n<p>Il percorso di visita si conclude con le ultime tre sale, articolate per temi: <em>soggetti religiosi e di storia, ritratto, <\/em>e infine<em> paesaggio e natura morta<\/em>. <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/09\/ROMA-PITTRICE-palazzo-braschi.jpg\" alt=\"ROMA PITTRICE. Artiste al lavoro tra XVI e XIX secolo\" class=\"wp-image-167190\"\/><\/figure>\n\n\n\n<p>A corredo della mostra anche <strong>un ciclo di incontri aperti al pubblico<\/strong> dove verranno toccati altri ambiti disciplinari in cui la presenza delle donne \u00e8 stata rilevante e ha lasciato il segno nel tempo, con ospiti internazionali. Sono inoltre in programma appuntamenti guidati accessibili a persone con disabilit\u00e0 visiva e uditiva.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-03627597 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/mostre-a-roma\/\">LE MIGLIORI MOSTRE A ROMA<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/la-tua-guida-ai-musei-di-roma\/\">GUIDA AI MUSEI DI ROMA<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong>Dal 25 ottobre 2024 al 4 maggio 2025&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Museo di Roma \u2013 Palazzo Braschi<\/strong> <br>Piazza San Pantaleo, 10 &#8211; Piazza Navona, 2 <\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Orari:<\/strong> Dal marted\u00ec alla domenica 10:00-19:00<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Biglietti: <\/strong>Intero \u20ac14, Ridotto \u20ac11<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.museodiroma.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">museodiroma.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fino al 23 marzo 2025 in esposizione oltre 130 opere, per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.<\/p>\n","protected":false},"author":1576,"featured_media":70601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[580,592],"tags":[],"class_list":["post-105083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-a-roma","category-mostre-a-roma"],"featured_image_src":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roma Pittrice, la mostra a Palazzo Braschi - Romeing<\/title>\n<meta name=\"description\" content=\"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROMA PITTRICE. Artiste al lavoro tra XVI e XVIII secolo in mostra a Palazzo Braschi\" \/>\n<meta property=\"og:description\" content=\"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/\" \/>\n<meta property=\"og:site_name\" content=\"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Romeing.it\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T09:33:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T20:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina Martinoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@romeing\" \/>\n<meta name=\"twitter:site\" content=\"@romeing\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina Martinoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/\"},\"author\":{\"name\":\"Valentina Martinoli\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\"},\"headline\":\"ROMA PITTRICE. Artiste al lavoro tra XVI e XVIII secolo in mostra a Palazzo Braschi\",\"datePublished\":\"2024-10-31T09:33:42+00:00\",\"dateModified\":\"2025-12-03T20:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/\"},\"wordCount\":569,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg\",\"articleSection\":[\"Eventi a Roma\",\"Mostre\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/\",\"name\":\"Roma Pittrice, la mostra a Palazzo Braschi - Romeing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg\",\"datePublished\":\"2024-10-31T09:33:42+00:00\",\"dateModified\":\"2025-12-03T20:27:48+00:00\",\"description\":\"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg\",\"width\":1200,\"height\":800,\"caption\":\"ROMA PITTRICE. Artiste al lavoro tra XVI e XIX secolo. Exhiibition at Palazzo Braschi in Rome\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"name\":\"Romeing: Rome's english magazine, events and exhibitions in Rome\",\"description\":\"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\",\"name\":\"Romeing srl\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"width\":696,\"height\":696,\"caption\":\"Romeing srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Romeing.it\",\"https:\\\/\\\/x.com\\\/romeing\",\"https:\\\/\\\/www.instagram.com\\\/romeing_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/romeing-srl\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/romeing\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@RomeingIt\"],\"email\":\"info@romeing.it\",\"legalName\":\"Romeing Srl\",\"foundingDate\":\"2010-12-01\",\"vatID\":\"11115241009\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\",\"name\":\"Valentina Martinoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"caption\":\"Valentina Martinoli\"},\"description\":\"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \\\"Beauty will save the world\\\".\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/author\\\/katiba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roma Pittrice, la mostra a Palazzo Braschi - Romeing","description":"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/","og_locale":"it_IT","og_type":"article","og_title":"ROMA PITTRICE. Artiste al lavoro tra XVI e XVIII secolo in mostra a Palazzo Braschi","og_description":"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.","og_url":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/","og_site_name":"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome","article_publisher":"https:\/\/www.facebook.com\/Romeing.it","article_published_time":"2024-10-31T09:33:42+00:00","article_modified_time":"2025-12-03T20:27:48+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","type":"image\/jpeg"}],"author":"Valentina Martinoli","twitter_card":"summary_large_image","twitter_creator":"@romeing","twitter_site":"@romeing","twitter_misc":{"Scritto da":"Valentina Martinoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#article","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/"},"author":{"name":"Valentina Martinoli","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a"},"headline":"ROMA PITTRICE. Artiste al lavoro tra XVI e XVIII secolo in mostra a Palazzo Braschi","datePublished":"2024-10-31T09:33:42+00:00","dateModified":"2025-12-03T20:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/"},"wordCount":569,"commentCount":0,"publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"image":{"@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","articleSection":["Eventi a Roma","Mostre"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.romeing.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/","url":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/","name":"Roma Pittrice, la mostra a Palazzo Braschi - Romeing","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#primaryimage"},"image":{"@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","datePublished":"2024-10-31T09:33:42+00:00","dateModified":"2025-12-03T20:27:48+00:00","description":"Fino al 4 maggio 2025 oltre 130 opere al Museo di Roma per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/roma-pittrice-artiste-al-lavoro-tra-xvi-e-xviii-secolo-in-mostra-a-palazzo-braschi\/#primaryimage","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg","width":1200,"height":800,"caption":"ROMA PITTRICE. Artiste al lavoro tra XVI e XIX secolo. Exhiibition at Palazzo Braschi in Rome"},{"@type":"WebSite","@id":"https:\/\/www.romeing.it\/it\/#website","url":"https:\/\/www.romeing.it\/it\/","name":"Romeing: Rome's english magazine, events and exhibitions in Rome","description":"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.","publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.romeing.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.romeing.it\/it\/#organization","name":"Romeing srl","url":"https:\/\/www.romeing.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","width":696,"height":696,"caption":"Romeing srl"},"image":{"@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Romeing.it","https:\/\/x.com\/romeing","https:\/\/www.instagram.com\/romeing_magazine\/","https:\/\/www.linkedin.com\/company\/romeing-srl\/","https:\/\/www.pinterest.it\/romeing\/pins\/","https:\/\/www.youtube.com\/@RomeingIt"],"email":"info@romeing.it","legalName":"Romeing Srl","foundingDate":"2010-12-01","vatID":"11115241009"},{"@type":"Person","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a","name":"Valentina Martinoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","caption":"Valentina Martinoli"},"description":"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \"Beauty will save the world\".","url":"https:\/\/www.romeing.it\/it\/author\/katiba\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg",1200,800,false],"thumbnail":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome-150x150.jpg",150,150,true],"medium":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome-768x512.jpg",768,512,true],"large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome-1024x683.jpg",800,534,true],"1536x1536":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg",1200,800,false],"2048x2048":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/ROMA-PITTRICE.-exhibition-palazzo-braschi-rome.jpg",1200,800,false]},"uagb_author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"uagb_comment_info":0,"uagb_excerpt":"Fino al 23 marzo 2025 in esposizione oltre 130 opere, per raccontare la presenza artistica delle donne nella Roma capitale delle Arti tra XVI e XIX secolo.","_links":{"self":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/users\/1576"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/comments?post=105083"}],"version-history":[{"count":2,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105083\/revisions"}],"predecessor-version":[{"id":105665,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105083\/revisions\/105665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media\/70601"}],"wp:attachment":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media?parent=105083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/categories?post=105083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/tags?post=105083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}