{"id":105249,"date":"2025-04-09T10:43:20","date_gmt":"2025-04-09T10:43:20","guid":{"rendered":"https:\/\/www.romeing.it\/barocco-globale-mostra-scuderie-del-quirinale\/"},"modified":"2025-12-03T14:15:54","modified_gmt":"2025-12-03T14:15:54","slug":"barocco-globale-mostra-scuderie-del-quirinale","status":"publish","type":"post","link":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/","title":{"rendered":"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-un-percorso-espositivo-che-proietta-la-luce-di-roma-ben-oltre-i-suoi-confini\">Un percorso espositivo che proietta la luce di Roma ben oltre i suoi confini<\/h2>\n\n\n\n<p>Busti di marmo policromo, arazzi monumentali, ritratti di diplomatici in missione in Oriente, animali esotici e abiti liturgici interamente decorati in piume. Visitando questa mostra si potrebbe avere l\u2019impressione di non essere a Roma ma di viaggiare in un luogo sospeso tra il mito, la storia religiosa e diplomazia globale.<\/p>\n\n\n\n<p>La mostra <em><strong>Barocco Globale. Il mondo a Roma nel secolo di Bernini <\/strong><\/em>visitabile alle <strong>Scuderie del Quirinale<\/strong> <strong>fino al 13 luglio<\/strong> \u00e8 la manifestazione artistica dell\u2019influenza e dell\u2019interconnessione della citt\u00e0 di Roma, dal punto di vista artistico, politico e diplomatico nel Seicento. Se l\u2019opulenza e lo splendore dell\u2019architettura e della pittura barocca sono ormai parte integrante dell\u2019immaginario di Roma, questa mostra svela il lato internazionale della citt\u00e0, del papato e del mondo politico del secolo del grande Bernini.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/031-scaled.jpg\" alt=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" class=\"wp-image-174906\"\/><figcaption class=\"wp-element-caption\">Gian Lorenzo Bernini, Modello per la Fontana dei Quattro Fiumi, 1647 &#8211; 1650 circa, Terracotta, legno intagliato, ardesia, oro e argento, Roma, Collezione Forti Bernini, Eredi Bernini<\/figcaption><\/figure>\n\n\n\n<p>Attraverso <strong>cento opere<\/strong> provenienti dai musei pi\u00f9 prestigiosi del mondo, il percorso testimonia la dimensione di una citt\u00e0 che ritroviamo fortemente globale, connessa tramite le sue istituzioni religiose, diplomatiche e artistiche al mondo intero, dall\u2019Africa all\u2019estremo Oriente. <\/p>\n\n\n\n<p>Barocco Globale \u00e8 un nuovo progetto espositivo curato da <strong>Francesca Cappelletti<\/strong> (Direttrice generale della Galleria Borghese e professore ordinario di Storia dell\u2019Arte all\u2019Universit\u00e0 di Ferrara) e <strong>Francesco Freddolini<\/strong> (professore associato di Storia dell\u2019arte presso \u2018Sapienza\u2019 Universit\u00e0 di Roma) e propone opere, sculture, disegni, incisioni, arazzi e manufatti eseguiti dai grandi artisti del secolo: <strong>Bernini, Van Dyck, Poussin,<\/strong> <strong>Pietro da Cortona, Lavinia Fontana, Nicolas Cordier, Pier Francesco Mola<\/strong> ed altri.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/084.jpg\" alt=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" class=\"wp-image-174914\"\/><figcaption class=\"wp-element-caption\">Manifacture royale des Gobelins, Lotta di animali, La Tenture des Indes, 6a serie, arazzo a tela alta, dal\ncartone di Albert Eckhout, 1644-1652)\n1723 &#8211; 1726, Paris\narazzo, Roma, Accademia di Francia a Roma &#8211; Villa Medici<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-roma-crocevia-di-cultura-e-potere\">Roma, crocevia di cultura e potere<\/h3>\n\n\n\n<p>\u201c<em>Roma \u00e8 l\u2019unico luogo dove qualunque forestiero si sente a casa<\/em>\u201d, scrisse nel 1581 Michel de Montaigne nel suo Viaggio in Italia. Questa dichiarazione riecheggia particolarmente bene all\u2019interno di un percorso espositivo che valorizza la storia di Roma per il suo respiro internazionale inclusivo e multiculturale. <\/p>\n\n\n\n<p>La mostra si apre in maniera scenografica con il busto in <strong>marmi policromi di Antonio Manuel Ne Vunda<\/strong>, Ambasciatore del Congo, realizzato nel 1608 da Antonio Caporale per il monumento funebre in Santa Maria Maggiore cui \u00e8 accostato. \u00c8 importante ricordare che questo fu l\u2019unico monumento funebre dedicato ad un uomo africano nell\u2019Europa della prima et\u00e0 moderna e la mostra ha permesso, grazie ad un restauro promosso dalle Scuderie del Quirinale, di poter vedere per la prima volta questo busto in circostanze ottimali e soprattutto in dialogo con altre opere che permettono di recuperarne la portata estetica e storica. L\u2019Egitto, l\u2019Africa e le Americhe sono infatti protagonisti del primo piano della mostra dove troviamo anche i <strong>primi modelli per la Fontana dei Fiumi realizzata per Piazza Navona dal Bernini<\/strong>, dipinti a olio raffiguranti scene di genere come La buona ventura di Bartolomeo Manfredi e il ritratto di un uomo africano di Albert Eckhout Santa Maria.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/066.jpg\" alt=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" class=\"wp-image-174912\"\/><figcaption class=\"wp-element-caption\">Francesco Caporale, Busto di Antonio Manuel Ne Vunda, 1608, marmi policromi, Citt\u00e0 del Vaticano, Basilica Papale di Santa Maria Maggiore, \u00a9 Capitolo di Santa Maria Maggiore, Citt\u00e0 del Vaticano<\/figcaption><\/figure>\n\n\n\n<p>Le altre sezioni della mostra sono dedicate al <strong>ruolo della Chiesa nel mondo<\/strong>, dove troviamo il ritratto di Nicolas Trigault in abiti cinesi, di Rubens, il mondo del collezionismo di piante ed animali rari, la diplomazia globale. Questa sezione presenta il ritratto di Ali-qoli Beg, ambasciatore persiano a Roma nel 1609, dipinto dalla pittrice Lavinia Fontana, un\u2019opera solo recentemente riscoperta e mai presentata al pubblico prima, ed un ritratto capace di far emergere i non scontati ed entusiasmanti rapporti tra Chiesa di Roma, Persia e donne pittrici all\u2019inizio del XVII secolo.<\/p>\n\n\n\n<p>Tra le altre opere di questo percorso troverete un parato ponteficale di fattura messicana fatta di seta, lino e piume colorate, una maschera raffigurante la divinit\u00e0 Yacatructli, gli scintillanti ritratti dei coniugi Shirley del fiammingo Sir Anthony van Dyck.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/054.jpg\" alt=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" class=\"wp-image-174908\"\/><figcaption class=\"wp-element-caption\">Sir Anthony van Dyck, Sir Robert Shirley , 1622, olio su tela, National Trust Collections, Petworth House (The Egremont Collection)<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/055.jpg\" alt=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" class=\"wp-image-174910\"\/><figcaption class=\"wp-element-caption\">Sir Anthony van Dyck, \nTeresa, or Teresia Sampsonia, Lady Shirley, 622\nolio su tela, National Trust Collections, Petworth House (The Egremont Collection)<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Barocco Globale stupisce con un racconto visivo di una Roma che, nel Seicento, si proponeva come uno dei centri pi\u00f9 attivi della cultura globale, dove arte, diplomazia e spiritualit\u00e0 si intrecciavano in un dialogo continuo tra continenti lontani.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-03627597 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/mostre-a-roma\/\">LE MIGLIORI MOSTRE A ROMA<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/la-tua-guida-ai-musei-di-roma\/\">GUIDA AI MUSEI DI ROMA<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong>Fino al 13 luglio 2025<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>SCUDERIE DEL QUIRINALE<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"> Via Ventiquattro Maggio, 16<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Orari:<\/strong> Luned\u00ec a domenica: 10 \u2013 20 (ultimo ingresso ore 19)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Biglietti:<\/strong> Intero 15\u20ac, Riduzioni applicabili<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/scuderiequirinale.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">scuderiequirinale.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale.<\/p>\n","protected":false},"author":2359,"featured_media":70964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[580,592],"tags":[],"class_list":["post-105249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-a-roma","category-mostre-a-roma"],"featured_image_src":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","author_info":{"display_name":"Paola Morotti","author_link":"https:\/\/www.romeing.it\/it\/author\/paolamorotti\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Barocco Globale - la nuova mostra alle Scuderie del Quirinale<\/title>\n<meta name=\"description\" content=\"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\" \/>\n<meta property=\"og:description\" content=\"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/\" \/>\n<meta property=\"og:site_name\" content=\"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Romeing.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T10:43:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T14:15:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"821\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paola Morotti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@romeing\" \/>\n<meta name=\"twitter:site\" content=\"@romeing\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paola Morotti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/\"},\"author\":{\"name\":\"Paola Morotti\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/cb721fd3c38a7504b19d4966ddbd7b7f\"},\"headline\":\"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale\",\"datePublished\":\"2025-04-09T10:43:20+00:00\",\"dateModified\":\"2025-12-03T14:15:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/\"},\"wordCount\":795,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/036BaroccoGlobale_0097-1-1024x701-1.jpg\",\"articleSection\":[\"Eventi a Roma\",\"Mostre\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/\",\"name\":\"Barocco Globale - la nuova mostra alle Scuderie del Quirinale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/036BaroccoGlobale_0097-1-1024x701-1.jpg\",\"datePublished\":\"2025-04-09T10:43:20+00:00\",\"dateModified\":\"2025-12-03T14:15:54+00:00\",\"description\":\"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/barocco-globale-mostra-scuderie-del-quirinale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/036BaroccoGlobale_0097-1-1024x701-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/036BaroccoGlobale_0097-1-1024x701-1.jpg\",\"width\":1200,\"height\":821,\"caption\":\"Copyright: \u00a9 Alberto Novelli per Scuderie Quirinale\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"name\":\"Romeing: Rome's english magazine, events and exhibitions in Rome\",\"description\":\"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\",\"name\":\"Romeing srl\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"width\":696,\"height\":696,\"caption\":\"Romeing srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Romeing.it\",\"https:\\\/\\\/x.com\\\/romeing\",\"https:\\\/\\\/www.instagram.com\\\/romeing_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/romeing-srl\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/romeing\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@RomeingIt\"],\"email\":\"info@romeing.it\",\"legalName\":\"Romeing Srl\",\"foundingDate\":\"2010-12-01\",\"vatID\":\"11115241009\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/cb721fd3c38a7504b19d4966ddbd7b7f\",\"name\":\"Paola Morotti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g\",\"caption\":\"Paola Morotti\"},\"description\":\"Paola Morotti, born and raised in Tuscany. She studied at the London School of Journalism. After six years of living in London, she is now based in Rome where she keeps writing about art exhibitions and cultural events.\",\"sameAs\":[\"https:\\\/\\\/www.paolamorotti.com\\\/\"],\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/author\\\/paolamorotti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barocco Globale - la nuova mostra alle Scuderie del Quirinale","description":"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/","og_locale":"it_IT","og_type":"article","og_title":"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale","og_description":"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.","og_url":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/","og_site_name":"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome","article_publisher":"https:\/\/www.facebook.com\/Romeing.it","article_published_time":"2025-04-09T10:43:20+00:00","article_modified_time":"2025-12-03T14:15:54+00:00","og_image":[{"width":1200,"height":821,"url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","type":"image\/jpeg"}],"author":"Paola Morotti","twitter_card":"summary_large_image","twitter_creator":"@romeing","twitter_site":"@romeing","twitter_misc":{"Scritto da":"Paola Morotti","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#article","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/"},"author":{"name":"Paola Morotti","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/cb721fd3c38a7504b19d4966ddbd7b7f"},"headline":"Barocco Globale. Il mondo a Roma nel secolo di Bernini alle Scuderie del Quirinale","datePublished":"2025-04-09T10:43:20+00:00","dateModified":"2025-12-03T14:15:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/"},"wordCount":795,"commentCount":0,"publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"image":{"@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","articleSection":["Eventi a Roma","Mostre"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.romeing.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/","url":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/","name":"Barocco Globale - la nuova mostra alle Scuderie del Quirinale","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#primaryimage"},"image":{"@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","datePublished":"2025-04-09T10:43:20+00:00","dateModified":"2025-12-03T14:15:54+00:00","description":"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale a Roma.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/barocco-globale-mostra-scuderie-del-quirinale\/#primaryimage","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg","width":1200,"height":821,"caption":"Copyright: \u00a9 Alberto Novelli per Scuderie Quirinale"},{"@type":"WebSite","@id":"https:\/\/www.romeing.it\/it\/#website","url":"https:\/\/www.romeing.it\/it\/","name":"Romeing: Rome's english magazine, events and exhibitions in Rome","description":"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.","publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.romeing.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.romeing.it\/it\/#organization","name":"Romeing srl","url":"https:\/\/www.romeing.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","width":696,"height":696,"caption":"Romeing srl"},"image":{"@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Romeing.it","https:\/\/x.com\/romeing","https:\/\/www.instagram.com\/romeing_magazine\/","https:\/\/www.linkedin.com\/company\/romeing-srl\/","https:\/\/www.pinterest.it\/romeing\/pins\/","https:\/\/www.youtube.com\/@RomeingIt"],"email":"info@romeing.it","legalName":"Romeing Srl","foundingDate":"2010-12-01","vatID":"11115241009"},{"@type":"Person","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/cb721fd3c38a7504b19d4966ddbd7b7f","name":"Paola Morotti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00fc9c76e4b30cf6bd2d9c9b29f4a96ea6ba13e54e1844771b76fe29b9821a0d?s=96&d=mm&r=g","caption":"Paola Morotti"},"description":"Paola Morotti, born and raised in Tuscany. She studied at the London School of Journalism. After six years of living in London, she is now based in Rome where she keeps writing about art exhibitions and cultural events.","sameAs":["https:\/\/www.paolamorotti.com\/"],"url":"https:\/\/www.romeing.it\/it\/author\/paolamorotti\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg",1200,821,false],"thumbnail":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1-300x205.jpg",300,205,true],"medium_large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1-768x525.jpg",768,525,true],"large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1-1024x701.jpg",800,548,true],"1536x1536":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg",1200,821,false],"2048x2048":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/036BaroccoGlobale_0097-1-1024x701-1.jpg",1200,821,false]},"uagb_author_info":{"display_name":"Paola Morotti","author_link":"https:\/\/www.romeing.it\/it\/author\/paolamorotti\/"},"uagb_comment_info":0,"uagb_excerpt":"Visita la mostra Barocco Globale. Il mondo a Roma nel secolo di Bernini nelle sale delle Scuderie del Quirinale.","_links":{"self":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/users\/2359"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/comments?post=105249"}],"version-history":[{"count":2,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105249\/revisions"}],"predecessor-version":[{"id":105487,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105249\/revisions\/105487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media\/70964"}],"wp:attachment":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media?parent=105249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/categories?post=105249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/tags?post=105249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}