{"id":105285,"date":"2025-07-06T11:51:53","date_gmt":"2025-07-06T11:51:53","guid":{"rendered":"https:\/\/www.romeing.it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/"},"modified":"2025-12-03T17:38:52","modified_gmt":"2025-12-03T17:38:52","slug":"la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte","status":"publish","type":"post","link":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/","title":{"rendered":"La fotografia di Elliott Erwitt a Palazzo Bonaparte"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-in-mostra-gli-scatti-sorprendenti-ed-ironici-del-grande-fotografo-statunitense\">In mostra gli scatti sorprendenti ed ironici del grande fotografo statunitense<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;occhio attento e ironico di <strong>Elliott Erwitt<\/strong>, maestro nel cogliere attraverso l&#8217;obiettivo fotografico le piccole e grandi assurdit\u00e0 della commedia umana ed animale, sar\u00e0 in mostra fino al <strong>21 Settembre<\/strong> nelle sale di <strong>Palazzo Bonaparte<\/strong> a Roma. <strong><em>Icons<\/em><\/strong>, la mostra a lui dedicata, curata da <strong>Biba Giacchetti <\/strong>e<strong> Gabriele Accornero<\/strong>, presentata da<strong> Arthemisia<\/strong> col supporto di <strong>Generali Valore Cultura<\/strong>, <strong>Fondazione Terzo Pilastro<\/strong> e <strong>Fondazione Cultura e Arte Poema<\/strong>, lo celebra con pi\u00f9 di <strong>80 scatti<\/strong> che ripercorrono la sua intera carriera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come lui stesso sosteneva, &#8220;<em>la fotografia \u00e8 l&#8217;arte di saper osservare&#8221;<\/em>. Un&#8217;arte che padroneggiava in pieno, visibile chiaramente dall&#8217;intensit\u00e0 psicologica delle foto scattate ai grandi personaggi del suo tempo, come nel caso del bellissimo ed intimo ritratto di <strong>Marylin Monroe<\/strong>. In mostra anche i ritratti di&nbsp;<strong>Che Guevara<\/strong>, <strong>Jack<\/strong> <strong>Kerouac<\/strong>, <strong>Marlene Dietrich<\/strong>,&nbsp;<strong>Fidel Castro<\/strong>,&nbsp;<strong>Sophia Loren<\/strong> e&nbsp;<strong>Arnold Schwarzenegger<\/strong>. Senza dimenticare le testimonianze storiche delle foto che ritraggono il&nbsp;<strong>diverbio tra Nixon e Krusciov<\/strong> e il&nbsp;funerale di<strong> Kennedy<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/06_1954.-MONROE-w-book.-30-x-40-scan_FINAL-print-Biba-1024x687.jpg\" alt=\"La fotografia di Elliot Erwitt a Palazzo Bonaparte a Roma.\" class=\"wp-image-177698\"\/><figcaption class=\"wp-element-caption\">Elliott Erwitt, USA.NewYork, 1956, \u00a9Elliott Erwitt\nPrivate Collection<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Membro della famosa <strong>Agenzia Magnum<\/strong> insieme ad altri grandi fotografi come <strong>Robert Capa <\/strong>e<strong> Henri Cartier Bresson<\/strong>, Erwitt \u00e8 riuscito a fare scuola, creando delle immagini davvero iconiche (da qui il titolo della mostra), in grado di restare impresse nella memoria. Immagini che invitano alla leggerezza e ad assumere una chiave di lettura del reale pi\u00f9 rilassata, incline alla meraviglia e alla sorpresa.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201cNei momenti pi\u00f9 tristi e invernali della vita, quando una nube ti avvolge da settimane, improvvisamente la visione di qualcosa di meraviglioso pu\u00f2 cambiare l\u2019aspetto delle cose, il tuo stato d\u2019animo. Il tipo di fotografia che piace a me, quella in cui viene colto l\u2019istante, \u00e8 molto simile a questo squarcio nelle nuvole. In un lampo, una foto meravigliosa sembra uscire fuori dal nulla\u201d.<\/em> Elliott Erwitt<\/p>\n<\/blockquote>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/05_USA.-NEW-YORK.2000-1024x686.jpg\" alt=\"Palazzo Bonaparte hosts the late Elliot Erwitt and his legacy of witty photography\" class=\"wp-image-177694\"\/><figcaption class=\"wp-element-caption\">Elliott Erwitt, USA. New York City, 2000, \u00a9Elliott Erwitt\nPrivate Collection<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Buffe, divertentissime e stranianti le immagini che ritraggono il mondo animale, in particolare i cani. Dalla donna bulldog, colta dal fotografo grazie a un rapido scatto fortunato ai buffi e tenerissimi chihuahua, abbigliati come bambini, che passeggiano fieri al fianco dei loro padroni. E ancora i magnifici cani barboni, giganteschi campioni di pedigree e toletta che assumono pose quasi umane, in un gioco di illusioni intelligenti sempre in grado di strappare un sorriso all&#8217;osservatore.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/08_ENGLAND.-Birmingham.-1991.-30-x-40-1024x683.jpg\" alt=\"La fotografia di Elliot Erwitt a Palazzo Bonaparte a Roma.\" class=\"wp-image-177700\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Suoi tratti distintivi l&#8217;attenzione per il dettaglio e il tempismo perfetto, insieme alla cura nell&#8217;immortalare qualsiasi soggetto, che si tratti di una diva del cinema o di una coppia di ignoti sposi, di un leader politico o di un cagnolino. Tutti i protagonisti delle fotografie di Erwitt infatti hanno la stessa importanza di fronte al suo obiettivo, a significare che tutta la realt\u00e0, nelle sue innumerevoli sfaccettature, vale la pena di essere osservata.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/01_USA.-New-York.-New-York-City.-1955-1024x685.jpg\" alt=\"Palazzo Bonaparte hosts the late Elliot Erwitt and his legacy of witty photography\" class=\"wp-image-177692\"\/><figcaption class=\"wp-element-caption\">Elliott Erwitt, USA.NewYorkCity. 1955, \u00a9Elliott Erwitt Private Collection<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-cbcdc57d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/mostre-a-roma\/\">LE MIGLIORI MOSTRE A ROMA<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.romeing.it\/it\/la-tua-guida-ai-musei-di-roma\/\">GUIDA AI MUSEI DI ROMA<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Fino al 21 Settembre 2025<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Palazzo Bonaparte<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Piazza Venezia, 5<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Orari:<\/strong> Tutti i giorni dalle 10.00 alle 20.00. Aperture prolungate il venerd\u00ec e il sabato<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Biglietti:<\/strong> Intero \u20ac16,50, Ridotto da \u20ac6,50 a \u20ac15,50<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/www.mostrepalazzobonaparte.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">mostrepalazzobonaparte.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita la mostra fotografica Elliot Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.<\/p>\n","protected":false},"author":1576,"featured_media":71004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[580,592],"tags":[],"class_list":["post-105285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-a-roma","category-mostre-a-roma"],"featured_image_src":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La fotografia di Elliott Erwitt a Palazzo Bonaparte - Romeing<\/title>\n<meta name=\"description\" content=\"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fotografia di Elliott Erwitt a Palazzo Bonaparte\" \/>\n<meta property=\"og:description\" content=\"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/\" \/>\n<meta property=\"og:site_name\" content=\"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Romeing.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-06T11:51:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T17:38:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"802\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina Martinoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@romeing\" \/>\n<meta name=\"twitter:site\" content=\"@romeing\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina Martinoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/\"},\"author\":{\"name\":\"Valentina Martinoli\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\"},\"headline\":\"La fotografia di Elliott Erwitt a Palazzo Bonaparte\",\"datePublished\":\"2025-07-06T11:51:53+00:00\",\"dateModified\":\"2025-12-03T17:38:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg\",\"articleSection\":[\"Eventi a Roma\",\"Mostre\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/\",\"name\":\"La fotografia di Elliott Erwitt a Palazzo Bonaparte - Romeing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg\",\"datePublished\":\"2025-07-06T11:51:53+00:00\",\"dateModified\":\"2025-12-03T17:38:52+00:00\",\"description\":\"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg\",\"width\":1200,\"height\":802,\"caption\":\"Elliott Erwitt, USA. New York City, 1974, \u00a9Elliott Erwitt\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"name\":\"Romeing: Rome's english magazine, events and exhibitions in Rome\",\"description\":\"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#organization\",\"name\":\"Romeing srl\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romeing.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-quadrato-romeing.jpg\",\"width\":696,\"height\":696,\"caption\":\"Romeing srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Romeing.it\",\"https:\\\/\\\/x.com\\\/romeing\",\"https:\\\/\\\/www.instagram.com\\\/romeing_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/romeing-srl\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/romeing\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@RomeingIt\"],\"email\":\"info@romeing.it\",\"legalName\":\"Romeing Srl\",\"foundingDate\":\"2010-12-01\",\"vatID\":\"11115241009\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/#\\\/schema\\\/person\\\/54e8bd3637f34425a9c6f5736631215a\",\"name\":\"Valentina Martinoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g\",\"caption\":\"Valentina Martinoli\"},\"description\":\"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \\\"Beauty will save the world\\\".\",\"url\":\"https:\\\/\\\/www.romeing.it\\\/it\\\/author\\\/katiba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La fotografia di Elliott Erwitt a Palazzo Bonaparte - Romeing","description":"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/","og_locale":"it_IT","og_type":"article","og_title":"La fotografia di Elliott Erwitt a Palazzo Bonaparte","og_description":"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.","og_url":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/","og_site_name":"Romeing | Rome&#039;s english magazine, events and exhibitions in Rome","article_publisher":"https:\/\/www.facebook.com\/Romeing.it","article_published_time":"2025-07-06T11:51:53+00:00","article_modified_time":"2025-12-03T17:38:52+00:00","og_image":[{"width":1200,"height":802,"url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","type":"image\/jpeg"}],"author":"Valentina Martinoli","twitter_card":"summary_large_image","twitter_creator":"@romeing","twitter_site":"@romeing","twitter_misc":{"Scritto da":"Valentina Martinoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#article","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/"},"author":{"name":"Valentina Martinoli","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a"},"headline":"La fotografia di Elliott Erwitt a Palazzo Bonaparte","datePublished":"2025-07-06T11:51:53+00:00","dateModified":"2025-12-03T17:38:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"image":{"@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","articleSection":["Eventi a Roma","Mostre"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.romeing.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/","url":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/","name":"La fotografia di Elliott Erwitt a Palazzo Bonaparte - Romeing","isPartOf":{"@id":"https:\/\/www.romeing.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#primaryimage"},"image":{"@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","datePublished":"2025-07-06T11:51:53+00:00","dateModified":"2025-12-03T17:38:52+00:00","description":"Visita la mostra fotografica Elliott Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/la-fotografia-di-elliot-erwitt-a-palazzo-bonaparte\/#primaryimage","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg","width":1200,"height":802,"caption":"Elliott Erwitt, USA. New York City, 1974, \u00a9Elliott Erwitt"},{"@type":"WebSite","@id":"https:\/\/www.romeing.it\/it\/#website","url":"https:\/\/www.romeing.it\/it\/","name":"Romeing: Rome's english magazine, events and exhibitions in Rome","description":"Romeing is the english magazine for tourists and expats visiting or living in Rome. A guide to the best things to do and see in Rome &amp; Florence, attractions and restaurants with a listing of events and exhibitions.","publisher":{"@id":"https:\/\/www.romeing.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.romeing.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.romeing.it\/it\/#organization","name":"Romeing srl","url":"https:\/\/www.romeing.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","contentUrl":"https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/logo-quadrato-romeing.jpg","width":696,"height":696,"caption":"Romeing srl"},"image":{"@id":"https:\/\/www.romeing.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Romeing.it","https:\/\/x.com\/romeing","https:\/\/www.instagram.com\/romeing_magazine\/","https:\/\/www.linkedin.com\/company\/romeing-srl\/","https:\/\/www.pinterest.it\/romeing\/pins\/","https:\/\/www.youtube.com\/@RomeingIt"],"email":"info@romeing.it","legalName":"Romeing Srl","foundingDate":"2010-12-01","vatID":"11115241009"},{"@type":"Person","@id":"https:\/\/www.romeing.it\/it\/#\/schema\/person\/54e8bd3637f34425a9c6f5736631215a","name":"Valentina Martinoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acb5e89aeba74afae8d7b6d28692cc0d6908d8267f8c94fa4a18470daa55cfbd?s=96&d=mm&r=g","caption":"Valentina Martinoli"},"description":"Valentina Martinoli is an italian art historian, journalist and content writer, based in Rome, specialised in cultural communication and exhibitions organisation. She fully agrees with Dostoevskij famous quote \"Beauty will save the world\".","url":"https:\/\/www.romeing.it\/it\/author\/katiba\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg",1200,802,false],"thumbnail":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs-150x150.jpg",150,150,true],"medium":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs-300x201.jpg",300,201,true],"medium_large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs-768x513.jpg",768,513,true],"large":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs-1024x684.jpg",800,534,true],"1536x1536":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg",1200,802,false],"2048x2048":["https:\/\/www.romeing.it\/wp-content\/uploads\/2025\/12\/02_PRINT_36-NYC.-1974.-Dog-legs.jpg",1200,802,false]},"uagb_author_info":{"display_name":"Valentina Martinoli","author_link":"https:\/\/www.romeing.it\/it\/author\/katiba\/"},"uagb_comment_info":0,"uagb_excerpt":"Visita la mostra fotografica Elliot Erwitt Icons, nelle sale di Palazzo Bonaparte a Roma fino al 21 Settembre 2025.","_links":{"self":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/users\/1576"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/comments?post=105285"}],"version-history":[{"count":2,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105285\/revisions"}],"predecessor-version":[{"id":105611,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/posts\/105285\/revisions\/105611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media\/71004"}],"wp:attachment":[{"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/media?parent=105285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/categories?post=105285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romeing.it\/it\/wp-json\/wp\/v2\/tags?post=105285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}